{"id":6844,"count":1,"description":"","link":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/","name":"Netflix original series","slug":"netflix-original-series","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Netflix original series Archives - Hollywood Jesus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix original series Archives - Hollywood Jesus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Hollywood Jesus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/tag\\\/netflix-original-series\\\/\",\"url\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/tag\\\/netflix-original-series\\\/\",\"name\":\"Netflix original series Archives - Hollywood Jesus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/tag\\\/netflix-original-series\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/tag\\\/netflix-original-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix original series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/\",\"name\":\"Hollywood Jesus\",\"description\":\"The Power of Story\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hollywoodjesus.com\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix original series Archives - Hollywood Jesus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/","og_locale":"en_US","og_type":"article","og_title":"Netflix original series Archives - Hollywood Jesus","og_url":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/","og_site_name":"Hollywood Jesus","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/","url":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/","name":"Netflix original series Archives - Hollywood Jesus","isPartOf":{"@id":"https:\/\/hollywoodjesus.com\/home\/#website"},"breadcrumb":{"@id":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hollywoodjesus.com\/home\/tag\/netflix-original-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hollywoodjesus.com\/home\/"},{"@type":"ListItem","position":2,"name":"Netflix original series"}]},{"@type":"WebSite","@id":"https:\/\/hollywoodjesus.com\/home\/#website","url":"https:\/\/hollywoodjesus.com\/home\/","name":"Hollywood Jesus","description":"The Power of Story","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hollywoodjesus.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/hollywoodjesus.com\/home\/wp-json\/wp\/v2\/tags\/6844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hollywoodjesus.com\/home\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hollywoodjesus.com\/home\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hollywoodjesus.com\/home\/wp-json\/wp\/v2\/posts?tags=6844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}